{"id":1005,"date":"2010-02-04T04:00:26","date_gmt":"2010-02-04T12:00:26","guid":{"rendered":"http:\/\/bluephi.net\/blog\/?p=1005"},"modified":"2014-12-02T15:37:14","modified_gmt":"2014-12-02T23:37:14","slug":"ebony-fashion-fair-models-ron-rod-fuller","status":"publish","type":"post","link":"https:\/\/bluephi.net\/blog\/2010\/02\/04\/ebony-fashion-fair-models-ron-rod-fuller\/","title":{"rendered":"Ebony Fashion Fair Models: Ron &#038; Rod Fuller"},"content":{"rendered":"<p>Ron &#038; Rod Fuller, well-known Dallas veteran <a href=\"http:\/\/books.google.com\/books?id=EbQDAAAAMBAJ&#038;pg=PA8&#038;lpg=PA8&#038;dq=rod+fuller+ebony+fashion+models&#038;source=bl&#038;ots=d-ZKrdUZR_&#038;sig=_jecI6jF29H6EgxL82SkjodSM24&#038;hl=en&#038;ei=fzASS8eVJIv8nAebvOjUAw&#038;sa=X&#038;oi=book_result&#038;ct=result&#038;resnum=8&#038;ved=0CBsQ6AEwBw#v=onepage&#038;q=rod%20fuller%20ebony%20fashion%20models&#038;f=false\">models from Ebony Fashion Fair are Sigma men<\/a>. They both pledged at Epsilon Zeta Chapter, Jarvis Christian College in Texas.<\/p>\n<p><a href=\"http:\/\/books.google.com\/books?id=r8wDAAAAMBAJ&#038;pg=PA76&#038;dq=rod+fuller&#038;as_pt=MAGAZINES#v=onepage&#038;q=rod%20fuller&#038;f=false\">More pics<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ron &#038; Rod Fuller, well-known Dallas veteran models from Ebony Fashion Fair are Sigma men. They both pledged at Epsilon Zeta Chapter, Jarvis Christian College in Texas. More pics<\/p>\n","protected":false},"author":11,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/bluephi.net\/blog\/wp-json\/wp\/v2\/posts\/1005"}],"collection":[{"href":"https:\/\/bluephi.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bluephi.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bluephi.net\/blog\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/bluephi.net\/blog\/wp-json\/wp\/v2\/comments?post=1005"}],"version-history":[{"count":3,"href":"https:\/\/bluephi.net\/blog\/wp-json\/wp\/v2\/posts\/1005\/revisions"}],"predecessor-version":[{"id":1300,"href":"https:\/\/bluephi.net\/blog\/wp-json\/wp\/v2\/posts\/1005\/revisions\/1300"}],"wp:attachment":[{"href":"https:\/\/bluephi.net\/blog\/wp-json\/wp\/v2\/media?parent=1005"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bluephi.net\/blog\/wp-json\/wp\/v2\/categories?post=1005"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bluephi.net\/blog\/wp-json\/wp\/v2\/tags?post=1005"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}